{"id":1162,"date":"2023-05-29T16:08:45","date_gmt":"2023-05-29T19:08:45","guid":{"rendered":"https:\/\/fundos-paladin.mz-sites.com\/corporativo\/botafogo-trade-center\/"},"modified":"2023-06-30T15:57:47","modified_gmt":"2023-06-30T18:57:47","slug":"botafogo-trade-center","status":"publish","type":"corporativo","link":"https:\/\/www.paladinrp.com.br\/en\/corporativo\/botafogo-trade-center\/","title":{"rendered":"Botafogo Trade Center"},"content":{"rendered":"","protected":false},"template":"","pais":[],"cidade":[],"estado":[],"class_list":["post-1162","corporativo","type-corporativo","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Botafogo Trade Center - Paladin | Fundos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.paladinrp.com.br\/en\/corporativo\/botafogo-trade-center\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Botafogo Trade Center - Paladin | Fundos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.paladinrp.com.br\/en\/corporativo\/botafogo-trade-center\/\" \/>\n<meta property=\"og:site_name\" content=\"Paladin | Fundos\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-30T18:57:47+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.paladinrp.com.br\\\/en\\\/corporativo\\\/botafogo-trade-center\\\/\",\"url\":\"https:\\\/\\\/www.paladinrp.com.br\\\/en\\\/corporativo\\\/botafogo-trade-center\\\/\",\"name\":\"Botafogo Trade Center - Paladin | Fundos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.paladinrp.com.br\\\/en\\\/#website\"},\"datePublished\":\"2023-05-29T19:08:45+00:00\",\"dateModified\":\"2023-06-30T18:57:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.paladinrp.com.br\\\/en\\\/corporativo\\\/botafogo-trade-center\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.paladinrp.com.br\\\/en\\\/corporativo\\\/botafogo-trade-center\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.paladinrp.com.br\\\/en\\\/corporativo\\\/botafogo-trade-center\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.paladinrp.com.br\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Botafogo Trade Center\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.paladinrp.com.br\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.paladinrp.com.br\\\/en\\\/\",\"name\":\"Paladin | Fundos\",\"description\":\"Gestora de Fundos\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.paladinrp.com.br\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Botafogo Trade Center - Paladin | Fundos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.paladinrp.com.br\/en\/corporativo\/botafogo-trade-center\/","og_locale":"en_US","og_type":"article","og_title":"Botafogo Trade Center - Paladin | Fundos","og_url":"https:\/\/www.paladinrp.com.br\/en\/corporativo\/botafogo-trade-center\/","og_site_name":"Paladin | Fundos","article_modified_time":"2023-06-30T18:57:47+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.paladinrp.com.br\/en\/corporativo\/botafogo-trade-center\/","url":"https:\/\/www.paladinrp.com.br\/en\/corporativo\/botafogo-trade-center\/","name":"Botafogo Trade Center - Paladin | Fundos","isPartOf":{"@id":"https:\/\/www.paladinrp.com.br\/en\/#website"},"datePublished":"2023-05-29T19:08:45+00:00","dateModified":"2023-06-30T18:57:47+00:00","breadcrumb":{"@id":"https:\/\/www.paladinrp.com.br\/en\/corporativo\/botafogo-trade-center\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.paladinrp.com.br\/en\/corporativo\/botafogo-trade-center\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.paladinrp.com.br\/en\/corporativo\/botafogo-trade-center\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.paladinrp.com.br\/en\/"},{"@type":"ListItem","position":2,"name":"Botafogo Trade Center"}]},{"@type":"WebSite","@id":"https:\/\/www.paladinrp.com.br\/en\/#website","url":"https:\/\/www.paladinrp.com.br\/en\/","name":"Paladin | Fundos","description":"Gestora de Fundos","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.paladinrp.com.br\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/www.paladinrp.com.br\/en\/wp-json\/wp\/v2\/corporativo\/1162","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.paladinrp.com.br\/en\/wp-json\/wp\/v2\/corporativo"}],"about":[{"href":"https:\/\/www.paladinrp.com.br\/en\/wp-json\/wp\/v2\/types\/corporativo"}],"wp:attachment":[{"href":"https:\/\/www.paladinrp.com.br\/en\/wp-json\/wp\/v2\/media?parent=1162"}],"wp:term":[{"taxonomy":"pais","embeddable":true,"href":"https:\/\/www.paladinrp.com.br\/en\/wp-json\/wp\/v2\/pais?post=1162"},{"taxonomy":"cidade","embeddable":true,"href":"https:\/\/www.paladinrp.com.br\/en\/wp-json\/wp\/v2\/cidade?post=1162"},{"taxonomy":"estado","embeddable":true,"href":"https:\/\/www.paladinrp.com.br\/en\/wp-json\/wp\/v2\/estado?post=1162"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}